{"id":1239,"date":"2019-05-28T09:18:32","date_gmt":"2019-05-28T07:18:32","guid":{"rendered":"http:\/\/www.fpvcrew.at\/wpfpvcrew\/?p=1239"},"modified":"2019-05-29T09:42:26","modified_gmt":"2019-05-29T07:42:26","slug":"horny-valley-2019","status":"publish","type":"post","link":"https:\/\/www.fpvcrew.at\/wpfpvcrew\/horny-valley-2019\/","title":{"rendered":"Two Days ago &#8211; Horny Valley 3.0"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1239\" class=\"elementor elementor-1239\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0e47724 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0e47724\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0dec29c\" data-id=\"0dec29c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3aa805f elementor-widget elementor-widget-image\" data-id=\"3aa805f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"474\" height=\"189\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/02\/49494439_2383142325089753_6062476029136470016_o-1024x409.png\" class=\"attachment-large size-large wp-image-975\" alt=\"\" srcset=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/02\/49494439_2383142325089753_6062476029136470016_o-1024x409.png 1024w, https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/02\/49494439_2383142325089753_6062476029136470016_o-300x120.png 300w, https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/02\/49494439_2383142325089753_6062476029136470016_o-768x307.png 768w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b894303 elementor-widget elementor-widget-text-editor\" data-id=\"b894303\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Zum dritten Mal in Folge fand das\u00a0<strong>Horny Valley<\/strong> Drohnen Rennen in K\u00e4rnten statt. Die FPV Crew Steiermark war mit 9 Mann am Start gewesen. (Patrick Sever, Manfred Herneth, Patrick, Florian Kollmann, Markus Hofbauer, Manuel Seiringer, Marcel Scherz, Markus Schriebl, Martin Fuchs)<\/p><p>Am Samstag fanden die Qualifikationsrunden\u00a0 statt.\u00a0 Der Tagesablauf wurde trotz Schlechtwetterprognose sehr gut \u00fcber die B\u00fchne gebracht. Blo\u00df am Nachmittag mussten wir eine Zwangspause von einer Stunde einlegen, da uns ein Regenguss \u00fcberrascht hat.\u00a0<\/p><p>Sonntag war Renntag! Die 16 schnellsten Piloten aus den Qualifikationsrunden haben sich f\u00fcr das Rennen qualifiziert. Darunter ist Florian Kollmann (Platz 6 -Quali.) und Manfred Herneth (Platz 9 -Quali.).<\/p><p>Es blieb bis zum Schluss der Double Elimination spannend,\u00a0 .. das Unglaubliche! Trotz starker Konkurrenz gelang es Florian Kollmann weiter in die letzte Finalrunde zu fliegen.<\/p><p>Endresultat &#8211; Finale:<\/p><p>1.Platz: J\u00fcrgen Stangl<\/p><p>2.Platz: Luisa Rizzo<\/p><p><strong>3.Platz: Florian Kollmann &#8211; FPV Crew Steiermark<\/strong><\/p><p>4.Platz: Walter Kirsch<\/p><p>Die Crew Gratuliert allen Piloten zu dieser Top Leistung.<\/p><p>Es hat uns sehr gefreut bekannte Gesichte zu treffen sowie neue kennen gelernt zu haben \ud83d\ude42<\/p><p><i>\u201eWir m\u00f6chten uns herzlichst bei Allen bedanken die das tolle Horny Valley Event auf die Beine gestellt haben, darunter ist Klaus Krieber, Lukas, Hermagor, Walter Kirsch, uvm. =DANKESCH\u00d6N. Einer der \u201eGailsten\u201c Event des Jahres.<\/i><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06c05ea elementor-widget elementor-widget-image\" data-id=\"06c05ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/hornyvalleyrace\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"474\" height=\"157\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/61681125_2697602746977041_6835878967744921600_o-1024x340.jpg\" class=\"attachment-large size-large wp-image-1285\" alt=\"\" srcset=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/61681125_2697602746977041_6835878967744921600_o-1024x340.jpg 1024w, https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/61681125_2697602746977041_6835878967744921600_o-300x100.jpg 300w, https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/61681125_2697602746977041_6835878967744921600_o-768x255.jpg 768w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-049a1f5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"049a1f5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a072d69\" data-id=\"a072d69\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-052d1d4 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"052d1d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:3000,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bild Karussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1162.jpg\" alt=\"_O8A1162\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1151.jpg\" alt=\"_O8A1151\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1134.jpg\" alt=\"_O8A1134\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1109.jpg\" alt=\"_O8A1109\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1149.jpg\" alt=\"_O8A1149\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1136.jpg\" alt=\"_O8A1136\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1150.jpg\" alt=\"_O8A1150\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1179.jpg\" alt=\"_O8A1179\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1166.jpg\" alt=\"_O8A1166\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1133.jpg\" alt=\"_O8A1133\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1132.jpg\" alt=\"_O8A1132\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1130.jpg\" alt=\"_O8A1130\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1128.jpg\" alt=\"_O8A1128\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1127.jpg\" alt=\"_O8A1127\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1126.jpg\" alt=\"_O8A1126\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"16 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1125.jpg\" alt=\"_O8A1125\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"17 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1124.jpg\" alt=\"_O8A1124\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"18 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1111.jpg\" alt=\"_O8A1111\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"19 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1112.jpg\" alt=\"_O8A1112\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"20 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1103.jpg\" alt=\"_O8A1103\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"21 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1114.jpg\" alt=\"_O8A1114\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"22 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1104.jpg\" alt=\"_O8A1104\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"23 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1115.jpg\" alt=\"_O8A1115\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"24 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1105.jpg\" alt=\"_O8A1105\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"25 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1116.jpg\" alt=\"_O8A1116\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"26 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1106.jpg\" alt=\"_O8A1106\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"27 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1107.jpg\" alt=\"_O8A1107\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"28 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1117.jpg\" alt=\"_O8A1117\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"29 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1118.jpg\" alt=\"_O8A1118\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"30 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1108.jpg\" alt=\"_O8A1108\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"31 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1120.jpg\" alt=\"_O8A1120\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"32 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1122.jpg\" alt=\"_O8A1122\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"33 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1110.jpg\" alt=\"_O8A1110\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"34 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1101.jpg\" alt=\"_O8A1101\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"35 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1100.jpg\" alt=\"_O8A1100\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"36 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/Siegerfoto-768x432.jpg\" alt=\"Siegerfoto\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"37 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1102.jpg\" alt=\"_O8A1102\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"38 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1135.jpg\" alt=\"_O8A1135\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"39 von 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-content\/uploads\/2019\/05\/O8A1146.jpg\" alt=\"_O8A1146\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5c5efe4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5c5efe4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b28eef7\" data-id=\"b28eef7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c559705 elementor-widget elementor-widget-video\" data-id=\"c559705\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=V3X88XN7_uU&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fffe24f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fffe24f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b844cd0\" data-id=\"b844cd0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-746eaa6 elementor-widget elementor-widget-text-editor\" data-id=\"746eaa6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"MsoNormal\">Interview mit <strong>Florian Kollmann<\/strong>:<\/p><p class=\"MsoNormal\"><b>[Crew:]<\/b> <i>Hey Flo, bitte stell dich an dieser Stelle kurz vor.<\/i><\/p><p class=\"MsoNormal\"><b>[Flo:]<\/b> <i>Ich hei\u00dfe Florian Kollmann, komme aus Krieglach und bin 19 Jahre alt.<\/i><\/p><p class=\"MsoNormal\"><b>[Crew:]<\/b> <i>Seit wann betreibst du das Hobby FPV Drone Racing? Wie oft trainierst du pro Woche? <\/i><\/p><p class=\"MsoNormal\"><b>[Flo:]<\/b> <i>Meinen ersten 5&#8243; Copter habe ich im April 2018 zusammengebaut. Aber durch den Stress w\u00e4hrend der Matura konnte ich erst Ende Juli 2018 richtig mit diesem Hobby starten. Ich trainiere so ziemlich jedes Wochenende, manchmal auch unter der Woche, auch wenn das Wetter nicht ganz so sch\u00f6n ist. Wenn das Wetter wirklich einmal nicht passt, trainiere ich daheim am PC \u00fcber einen Simulator. Mein momentaner Lieblingssimulator ist Velocidrone.<\/i><\/p><p class=\"MsoNormal\"><b>[Crew:]<\/b> <i>3. Platz beim Horny Valley, Wahnsinns Ergebnis, Kannst du uns kurz vergangenes Wochenende zusammenfassen?<\/i><\/p><p class=\"MsoNormal\"><b>[Flo:]<\/b> <i>Es war ein super Wochenende mit Freunden, Kollegen und neuen Bekanntschaften. Dieses Wochenende zeigte mir wieder einmal wie freundlich jeder ist und dass jeder, jeden helfen will.<\/i><\/p><p class=\"MsoNormal\"><b>[Crew:]<\/b> <i>Mit welchen Setup, bist du an den Start gegangen und warum?<\/i><\/p><p class=\"MsoNormal\"><b>[Flo:]<\/b> <i>Hauptbestandteil meines Setups ist der spezielle Rahmen. Es ist ein &#8222;vertical box frame&#8220; mit den Namen &#8222;Staccato&#8220; von Cherrycraft. Durch seine einzigartigen Flugeigenschaften kann ich genauer und schneller fliegen als mit einem herk\u00f6mmlichen Rahmen. Den ESC den ich verwende ist ein T-Motor F45A 4in1, der 4 St\u00fcck XNova 2207 1700kv, gepaart mit Gemfan hurricane 51466&#215;3 propeller, mit Saft vom 6S SLS Xtron 1300mah-Akku versorgt. Der verbaute Flugcontroller ist ein RevoltOSD von Flightone. Auf diesem Flugcontroller h\u00e4ngt ein TBS Crossfire nano Empf\u00e4nger, der mir eine solide Verbindung zur Fernsteuerung sicherstellt. Ebenfalls von TBS ist der Unify pro32 nano Videotransmitter, der das Bild von der Runcam Swift 2 mit Leichtigkeit, \u00fcber die Lollipop-Antenne von Foxeer, an meine Videobrille \u00fcbertr\u00e4gt.<\/i><\/p><p class=\"MsoNormal\"><i>Danke an Martin Klinglmayr von kwadstore.at und Walter Kirsch von Cherrycraft f\u00fcr eure Unterst\u00fctzung!<\/i><\/p><p class=\"MsoNormal\"><b>[Crew:]<\/b> <i>Fast &#8211; Faster &#8211; Florian &#8211; Danke f\u00fcr das Interview \ud83d\ude42<\/i><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ed5c138 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ed5c138\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bea72d0\" data-id=\"bea72d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c8421b4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c8421b4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6cf5067\" data-id=\"6cf5067\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6400158 elementor-shape-rounded elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"6400158\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-8c4175d\" href=\"https:\/\/www.facebook.com\/fpvcrewstmk\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-facebook\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Zum dritten Mal in Folge fand das\u00a0Horny Valley Drohnen Rennen in K\u00e4rnten statt. Die FPV Crew Steiermark war mit 9 Mann am Start gewesen. (Patrick Sever, Manfred Herneth, Patrick, Florian Kollmann, Markus Hofbauer, Manuel Seiringer, Marcel Scherz, Markus Schriebl, Martin Fuchs) Am Samstag fanden die Qualifikationsrunden\u00a0 statt.\u00a0 Der Tagesablauf wurde trotz Schlechtwetterprognose sehr gut \u00fcber &hellip; <a href=\"https:\/\/www.fpvcrew.at\/wpfpvcrew\/horny-valley-2019\/\" class=\"more-link\"><span class=\"screen-reader-text\">Two Days ago &#8211; Horny Valley 3.0<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":1235,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[60,5,36,4,59,58,61,57],"class_list":["post-1239","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-events","tag-cherrycraft","tag-crew","tag-drone-racing","tag-fpv","tag-horny-valley","tag-impression","tag-kwadstore-at","tag-results"],"_links":{"self":[{"href":"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-json\/wp\/v2\/posts\/1239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-json\/wp\/v2\/comments?post=1239"}],"version-history":[{"count":22,"href":"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-json\/wp\/v2\/posts\/1239\/revisions"}],"predecessor-version":[{"id":1302,"href":"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-json\/wp\/v2\/posts\/1239\/revisions\/1302"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-json\/wp\/v2\/media\/1235"}],"wp:attachment":[{"href":"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-json\/wp\/v2\/media?parent=1239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-json\/wp\/v2\/categories?post=1239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fpvcrew.at\/wpfpvcrew\/wp-json\/wp\/v2\/tags?post=1239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}